{"id":135419,"date":"2025-08-03T08:17:15","date_gmt":"2025-08-03T12:17:15","guid":{"rendered":"https:\/\/www.aa87.org\/message-du-directeur-general-de-bsg-29-juillet-2025\/"},"modified":"2025-08-03T08:21:51","modified_gmt":"2025-08-03T12:21:51","slug":"message-du-directeur-general-de-bsg-29-juillet-2025","status":"publish","type":"post","link":"https:\/\/www.aa87.org\/es\/message-du-directeur-general-de-bsg-29-juillet-2025\/","title":{"rendered":"Mensaje del director general de GSO &#8211; 29 de julio de 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"135419\" class=\"elementor elementor-135419 elementor-135412\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33de3b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33de3b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e008732\" data-id=\"e008732\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13c8f69 elementor-widget elementor-widget-text-editor\" data-id=\"13c8f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><div><p><span class=\"font-arial\">29 de julio de 2025<\/span><\/p><p><span class=\"font-arial\">A: RSG, MCD, custodios, directores no custodios, servidores y coordinadores de comit\u00e9s de \u00e1rea, delegados, miembros de comit\u00e9 invitados, intergrupos y oficinas centrales, contactos de los grupos, empleados de la OSG y del Grapevine<\/span><\/p><p><span class=\"font-arial\">Estimados amigos de AA:<\/span><\/p><p><span class=\"font-arial\">Quiero aprovechar esta oportunidad para expresar mi profunda gratitud a todos los que asistieron a la Convenci\u00f3n Internacional que se celebr\u00f3 en Vancouver, Columbia Brit\u00e1nica, Canad\u00e1, a principios de este mes, y a los que dieron su apoyo a la misma. M\u00e1s de 34,000 miembros e invitados de m\u00e1s de 90 pa\u00edses estuvieron presentes para celebrar el nonag\u00e9simo aniversario de nuestra Comunidad. Realmente se trat\u00f3 de una extraordinaria reuni\u00f3n de amor y servicio. Estar con decenas de miles de miembros de AA de todo el mundo fue un poderoso recordatorio de la profundidad y el alcance de nuestra Comunidad, y la alegr\u00eda que surge de compartir nuestra sobriedad un d\u00eda a la vez.<\/span><\/p><p><span class=\"font-arial\">En mi \u00faltima comunicaci\u00f3n, mencion\u00e9 que las operaciones del octavo y el und\u00e9cimo pisos de la Oficina de Servicios Generales se consolidar\u00e1n \u00fanicamente en el piso once. Esto no solo permitir\u00e1 ahorrar en costos de ocupaci\u00f3n, sino tambi\u00e9n mejorar la colaboraci\u00f3n y la eficacia entre todos los departamentos y servicios que prestamos. Esta consolidaci\u00f3n requerir\u00e1 modificaciones en nuestras oficinas para dar cabida a los departamentos de Publicaciones y Servicios de Comunicaci\u00f3n, que ahora se encuentran en el octavo piso.<\/span><\/p><p><span class=\"font-arial\">En los \u00faltimos meses hemos dedicado mucho tiempo y esfuerzo a planificar la remodelaci\u00f3n de nuestro espacio. Para mantener al m\u00ednimo los costos asociados y minimizar la interrupci\u00f3n de los servicios, la oficina funcionar\u00e1 a distancia a partir del lunes 11 de agosto, mientras dure el proyecto, cuyo tiempo de ejecuci\u00f3n se prev\u00e9 que tome entre diez y doce semanas. Queremos que sepan que el correo y los env\u00edos, as\u00ed como nuestros tel\u00e9fonos, seguir\u00e1n estando operativos en todo momento. Lamentablemente, no ser\u00e1 posible visitar la oficina durante este tiempo, pero las visitas a la OSG se reanudar\u00e1n cuando finalice el proyecto. Para obtener informaci\u00f3n actualizada durante este periodo, consulte\u00a0<a href=\"https:\/\/aaworldservicesinc.createsend1.com\/t\/y-l-qjhdkjk-ikhisqir-i\/\" data-emb-iscopy=\"true\">aa.org<\/a>,\u00a0<a href=\"https:\/\/aaworldservicesinc.createsend1.com\/t\/y-l-qjhdkjk-ikhisqir-d\/\" data-emb-iscopy=\"true\">aagrapevine.org<\/a>, la aplicaci\u00f3n Meeting Guide, as\u00ed como las aplicaciones del Grapevine y La Vi\u00f1a.<\/span><\/p><p><span class=\"font-arial\">Somos conscientes de que muchos de ustedes pueden estar planeando visitas a la OSG, y les pedimos sinceras disculpas por las molestias que esto pueda causarles. Esperamos volver a darles la bienvenida a una OSG renovada y revitalizada este oto\u00f1o. Muchas gracias por su paciencia y su comprensi\u00f3n durante este proyecto.<\/span><\/p><p><span class=\"font-arial\">Con gratitud por su servicio constante a Alcoh\u00f3licos An\u00f3nimos,<\/span><\/p><\/div><\/div><div><div align=\"left\"><img decoding=\"async\" src=\"https:\/\/i3.createsend1.com\/ei\/y\/0E\/AD8\/993\/031738\/csfinal\/BobWSignature22-9900000b6d3cf03c.PNG\" alt=\"\" width=\"90\" \/><\/div><\/div><div><div><p><span class=\"font-arial\">Bob W.<br \/>Gerente general de la OSG<\/span><\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>29 de julio de 2025 A: RSG, MCD, custodios, directores no custodios, servidores y coordinadores de comit\u00e9s de \u00e1rea, delegados, miembros de comit\u00e9 invitados, intergrupos y oficinas centrales, contactos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[519],"tags":[],"class_list":["post-135419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-delegar"],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:38:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/posts\/135419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/comments?post=135419"}],"version-history":[{"count":4,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/posts\/135419\/revisions"}],"predecessor-version":[{"id":135423,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/posts\/135419\/revisions\/135423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/media\/77335"}],"wp:attachment":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/media?parent=135419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/categories?post=135419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tags?post=135419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}