{"id":10008409,"date":"2024-10-16T14:25:54","date_gmt":"2024-10-16T18:25:54","guid":{"rendered":"https:\/\/www.aa87.org\/?post_type=tribe_events&#038;p=123388"},"modified":"2024-10-18T01:17:50","modified_gmt":"2024-10-18T05:17:50","slug":"rq1017","status":"publish","type":"tribe_events","link":"https:\/\/www.aa87.org\/es\/evenement\/rq1017\/2025-10-17\/","title":{"rendered":"Reflexi\u00f3n diaria 17 de octubre"},"content":{"rendered":"<h3><span class=\"field field--name-title field--type-string field--label-hidden\">Uu reajuste diario<\/span><\/h3>\n<div>17 de octubre<\/div>\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p><strong>Cada d\u00eda es un d\u00eda en el que tenemos que llevar la visi\u00f3n de la voluntad de Dios a todos nuestros actos.<\/strong><\/p>\n<p><strong>Alcoh\u00f3licos An\u00f3nimos, p. 85<\/strong><\/p>\n<p>\u00bfC\u00f3mo mantengo mi condici\u00f3n espiritual? Para m\u00ed es muy sencillo: cada d\u00eda le pido a mi Poder Superior que me conceda el don de la sobriedad por ese d\u00eda. Yo he hablado con muchos alcoh\u00f3licos que han vuelto a beber y siempre les pregunto: \u201c\u00bfOraste pidiendo la sobriedad el d\u00eda en que tomaste tu primer trago?\u201d Ninguno de ellos dijo que s\u00ed. Seg\u00fan practico el Paso Diez y trato de mantener mi casa en orden diariamente, tengo la seguridad de que si pido el indulto diario, se me conceder\u00e1.<\/p>\n<\/div>\n<div class=\"copyright-block\">\n<p><strong>Del libro\u00a0<em>Reflexiones diarias<\/em><br \/>\nCopyright \u00a9 1991 por Alcoholics Anonymous World Services, Inc. Todos los derechos reservados.<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.aa87.org\/es\/ressources\/rq\/\">Todas las reflexiones diarias<\/a><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uu reajuste diario 17 de octubre Cada d\u00eda es un d\u00eda en el que tenemos que llevar la visi\u00f3n de la voluntad de Dios a todos nuestros actos. Alcoh\u00f3licos An\u00f3nimos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[656],"class_list":["post-10008409","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-reflexion-quotidiennes-es","cat_reflexion-quotidiennes-es","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events\/10008409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events\/10008409\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/media?parent=10008409"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tags?post=10008409"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10008409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}