{"id":10022819,"date":"2025-07-12T08:40:06","date_gmt":"2025-07-12T12:40:06","guid":{"rendered":"https:\/\/www.aa87.org\/?post_type=tribe_events&#038;p=134195"},"modified":"2025-07-12T09:01:55","modified_gmt":"2025-07-12T13:01:55","slug":"rq0720-2","status":"publish","type":"tribe_events","link":"https:\/\/www.aa87.org\/es\/evenement\/rq0720-2\/2025-07-20\/","title":{"rendered":"Reflexi\u00f3n diaria 20 de julio"},"content":{"rendered":"<h3><span class=\"field field--name-title field--type-string field--label-hidden\">Liberados de defectos<\/span><\/h3>\n<div>20 de julio<\/div>\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p><strong>Pero ahora las palabras \u201cPor m\u00ed mismo nada soy, el Padre hace las obras\u201d empezaban a cobrar un significado muy prometedor.<\/strong><\/p>\n<p><strong>Doce pasos y doce traditions, p. 72<\/strong><\/p>\n<p>Cuando pongo el S\u00e9ptimo Paso en acci\u00f3n debo recordar exactamente lo que dice. No dice \u201cHumildemente le pedimos que nos ayudara o que nos diera la fortaleza o el valor para libramos de nuestros defectos\u201d. El Paso dice simplemente que Dios me librar\u00e1 de mis defectos. El \u00fanico trabajo que tengo que hacer es \u201cpedir humildemente\u201d, lo cual, para m\u00ed, significa pedir con el conocimiento de que yo por m\u00ed mismo soy nada, el Padre dentro de m\u00ed \u201chace las obras\u201d.<\/p>\n<p><strong>Del libro\u00a0<em>Reflexiones diarias<\/em><br \/>\nCopyright \u00a9 1991 por Alcoholics Anonymous World Services, Inc. Todos los derechos reservados.<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.aa87.org\/es\/ressources\/rq\/\">Todas las reflexiones diarias<\/a><\/strong><\/p>\n<\/div>\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Liberados de defectos 20 de julio Pero ahora las palabras \u201cPor m\u00ed mismo nada soy, el Padre hace las obras\u201d empezaban a cobrar un significado muy prometedor. Doce pasos y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10022819","tribe_events","type-tribe_events","status-publish","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events\/10022819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events\/10022819\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/media?parent=10022819"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tags?post=10022819"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.aa87.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=10022819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}